{"id":1298,"date":"2020-06-20T22:41:25","date_gmt":"2020-06-21T01:41:25","guid":{"rendered":"https:\/\/vivadoctor.com.br\/cid\/?p=1298"},"modified":"2020-06-20T22:41:27","modified_gmt":"2020-06-21T01:41:27","slug":"h48","status":"publish","type":"post","link":"https:\/\/vivadoctor.com.br\/cid\/h48\/","title":{"rendered":"H48 &#8211; Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte"},"content":{"rendered":"\n<p>H480 &#8211; Atrofia \u00f3ptica em doen\u00e7as classificadas em outra parte<\/p>\n\n\n\n<p>H481 &#8211; Neurite retrobulbar em doen\u00e7as classificadas em outra parte<\/p>\n\n\n\n<p>H488 &#8211; Outros transtornos do nervo \u00f3ptico e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H480 &#8211; Atrofia \u00f3ptica em doen\u00e7as classificadas em outra parte H481 &#8211; Neurite retrobulbar em doen\u00e7as classificadas em outra parte H488 &#8211; Outros transtornos do nervo \u00f3ptico e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[85,89],"tags":[2108,2105,2109],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>H48 - Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte - Consulta CID 10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vivadoctor.com.br\/cid\/h48\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H48 - Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte - Consulta CID 10\" \/>\n<meta property=\"og:description\" content=\"H480 &#8211; Atrofia \u00f3ptica em doen\u00e7as classificadas em outra parte H481 &#8211; Neurite retrobulbar em doen\u00e7as classificadas em outra parte H488 &#8211; Outros transtornos do nervo \u00f3ptico e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vivadoctor.com.br\/cid\/h48\/\" \/>\n<meta property=\"og:site_name\" content=\"Consulta CID 10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/doutorapp\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/doutorapp\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-21T01:41:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-21T01:41:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DoutorApp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/\",\"name\":\"Consulta CID 10\",\"description\":\"Classifica\\u00e7\\u00e3o Internacional de Doen\\u00e7as\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/h48\/#webpage\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/h48\/\",\"name\":\"H48 - Transtornos do nervo \\u00f3ptico [segundo par] e das vias \\u00f3pticas em doen\\u00e7as classificadas em outra parte - Consulta CID 10\",\"isPartOf\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\"},\"datePublished\":\"2020-06-21T01:41:25+00:00\",\"dateModified\":\"2020-06-21T01:41:27+00:00\",\"author\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1\"},\"breadcrumb\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/h48\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vivadoctor.com.br\/cid\/h48\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/h48\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/vivadoctor.com.br\/cid\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H48 &#8211; Transtornos do nervo \\u00f3ptico [segundo par] e das vias \\u00f3pticas em doen\\u00e7as classificadas em outra parte\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1\",\"name\":\"DoutorApp\",\"sameAs\":[\"https:\/\/vivadoctor.com.br\/cid\",\"https:\/\/facebook.com\/doutorapp\",\"https:\/\/instagram.com\/doutorapp\"],\"url\":\"https:\/\/vivadoctor.com.br\/cid\/author\/edimar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H48 - Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte - Consulta CID 10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vivadoctor.com.br\/cid\/h48\/","og_locale":"pt_BR","og_type":"article","og_title":"H48 - Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte - Consulta CID 10","og_description":"H480 &#8211; Atrofia \u00f3ptica em doen\u00e7as classificadas em outra parte H481 &#8211; Neurite retrobulbar em doen\u00e7as classificadas em outra parte H488 &#8211; Outros transtornos do nervo \u00f3ptico e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte","og_url":"https:\/\/vivadoctor.com.br\/cid\/h48\/","og_site_name":"Consulta CID 10","article_publisher":"https:\/\/facebook.com\/doutorapp","article_author":"https:\/\/facebook.com\/doutorapp","article_published_time":"2020-06-21T01:41:25+00:00","article_modified_time":"2020-06-21T01:41:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"DoutorApp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/vivadoctor.com.br\/cid\/#website","url":"https:\/\/vivadoctor.com.br\/cid\/","name":"Consulta CID 10","description":"Classifica\u00e7\u00e3o Internacional de Doen\u00e7as","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/vivadoctor.com.br\/cid\/h48\/#webpage","url":"https:\/\/vivadoctor.com.br\/cid\/h48\/","name":"H48 - Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte - Consulta CID 10","isPartOf":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#website"},"datePublished":"2020-06-21T01:41:25+00:00","dateModified":"2020-06-21T01:41:27+00:00","author":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1"},"breadcrumb":{"@id":"https:\/\/vivadoctor.com.br\/cid\/h48\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vivadoctor.com.br\/cid\/h48\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vivadoctor.com.br\/cid\/h48\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vivadoctor.com.br\/cid\/"},{"@type":"ListItem","position":2,"name":"H48 &#8211; Transtornos do nervo \u00f3ptico [segundo par] e das vias \u00f3pticas em doen\u00e7as classificadas em outra parte"}]},{"@type":"Person","@id":"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1","name":"DoutorApp","sameAs":["https:\/\/vivadoctor.com.br\/cid","https:\/\/facebook.com\/doutorapp","https:\/\/instagram.com\/doutorapp"],"url":"https:\/\/vivadoctor.com.br\/cid\/author\/edimar\/"}]}},"_links":{"self":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1298"}],"collection":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/comments?post=1298"}],"version-history":[{"count":1,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1298\/revisions"}],"predecessor-version":[{"id":1299,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1298\/revisions\/1299"}],"wp:attachment":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/media?parent=1298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/categories?post=1298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/tags?post=1298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}