{"id":1708,"date":"2020-06-27T21:30:17","date_gmt":"2020-06-28T00:30:17","guid":{"rendered":"https:\/\/vivadoctor.com.br\/cid\/?p=1708"},"modified":"2020-06-27T21:30:21","modified_gmt":"2020-06-28T00:30:21","slug":"k28","status":"publish","type":"post","link":"https:\/\/vivadoctor.com.br\/cid\/k28\/","title":{"rendered":"K28 &#8211; \u00dalcera gastrojejunal"},"content":{"rendered":"\n<p>K280 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia<\/p>\n\n\n\n<p>K281 &#8211; \u00dalcera gastrojejunal &#8211; aguda com perfura\u00e7\u00e3o<\/p>\n\n\n\n<p>K282 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia e perfura\u00e7\u00e3o<\/p>\n\n\n\n<p>K283 &#8211; \u00dalcera gastrojejunal &#8211; aguda sem hemorragia ou perfura\u00e7\u00e3o<\/p>\n\n\n\n<p>K284 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o especificada com hemorragia<\/p>\n\n\n\n<p>K285 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o especificada com perfura\u00e7\u00e3o<\/p>\n\n\n\n<p>K286 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o especificada com hemorragia e perfura\u00e7\u00e3o<\/p>\n\n\n\n<p>K287 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica sem hemorragia ou perfura\u00e7\u00e3o<\/p>\n\n\n\n<p>K289 &#8211; \u00dalcera gastrojejunal &#8211; n\u00e3o especificada como aguda ou cr\u00f4nica, sem hemorragia ou perfura\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K280 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia K281 &#8211; \u00dalcera gastrojejunal &#8211; aguda com perfura\u00e7\u00e3o K282 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia e perfura\u00e7\u00e3o K283 &#8211; \u00dalcera gastrojejunal &#8211; aguda sem hemorragia ou perfura\u00e7\u00e3o K284 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o especificada com hemorragia K285 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o<a class=\"more-link\" href=\"https:\/\/vivadoctor.com.br\/cid\/k28\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[124,133],"tags":[1746,2750,2751,2753],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>K28 - \u00dalcera gastrojejunal - Consulta CID 10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vivadoctor.com.br\/cid\/k28\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K28 - \u00dalcera gastrojejunal - Consulta CID 10\" \/>\n<meta property=\"og:description\" content=\"K280 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia K281 &#8211; \u00dalcera gastrojejunal &#8211; aguda com perfura\u00e7\u00e3o K282 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia e perfura\u00e7\u00e3o K283 &#8211; \u00dalcera gastrojejunal &#8211; aguda sem hemorragia ou perfura\u00e7\u00e3o K284 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o especificada com hemorragia K285 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3oContinue lendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vivadoctor.com.br\/cid\/k28\/\" \/>\n<meta property=\"og:site_name\" content=\"Consulta CID 10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/doutorapp\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/doutorapp\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-28T00:30:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-28T00:30:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DoutorApp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/\",\"name\":\"Consulta CID 10\",\"description\":\"Classifica\\u00e7\\u00e3o Internacional de Doen\\u00e7as\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/k28\/#webpage\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/k28\/\",\"name\":\"K28 - \\u00dalcera gastrojejunal - Consulta CID 10\",\"isPartOf\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\"},\"datePublished\":\"2020-06-28T00:30:17+00:00\",\"dateModified\":\"2020-06-28T00:30:21+00:00\",\"author\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1\"},\"breadcrumb\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/k28\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vivadoctor.com.br\/cid\/k28\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/k28\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/vivadoctor.com.br\/cid\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K28 &#8211; \\u00dalcera gastrojejunal\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1\",\"name\":\"DoutorApp\",\"sameAs\":[\"https:\/\/vivadoctor.com.br\/cid\",\"https:\/\/facebook.com\/doutorapp\",\"https:\/\/instagram.com\/doutorapp\"],\"url\":\"https:\/\/vivadoctor.com.br\/cid\/author\/edimar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K28 - \u00dalcera gastrojejunal - Consulta CID 10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vivadoctor.com.br\/cid\/k28\/","og_locale":"pt_BR","og_type":"article","og_title":"K28 - \u00dalcera gastrojejunal - Consulta CID 10","og_description":"K280 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia K281 &#8211; \u00dalcera gastrojejunal &#8211; aguda com perfura\u00e7\u00e3o K282 &#8211; \u00dalcera gastrojejunal &#8211; aguda com hemorragia e perfura\u00e7\u00e3o K283 &#8211; \u00dalcera gastrojejunal &#8211; aguda sem hemorragia ou perfura\u00e7\u00e3o K284 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3o especificada com hemorragia K285 &#8211; \u00dalcera gastrojejunal &#8211; cr\u00f4nica ou n\u00e3oContinue lendo &rarr;","og_url":"https:\/\/vivadoctor.com.br\/cid\/k28\/","og_site_name":"Consulta CID 10","article_publisher":"https:\/\/facebook.com\/doutorapp","article_author":"https:\/\/facebook.com\/doutorapp","article_published_time":"2020-06-28T00:30:17+00:00","article_modified_time":"2020-06-28T00:30:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"DoutorApp","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/vivadoctor.com.br\/cid\/#website","url":"https:\/\/vivadoctor.com.br\/cid\/","name":"Consulta CID 10","description":"Classifica\u00e7\u00e3o Internacional de Doen\u00e7as","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/vivadoctor.com.br\/cid\/k28\/#webpage","url":"https:\/\/vivadoctor.com.br\/cid\/k28\/","name":"K28 - \u00dalcera gastrojejunal - Consulta CID 10","isPartOf":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#website"},"datePublished":"2020-06-28T00:30:17+00:00","dateModified":"2020-06-28T00:30:21+00:00","author":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1"},"breadcrumb":{"@id":"https:\/\/vivadoctor.com.br\/cid\/k28\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vivadoctor.com.br\/cid\/k28\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vivadoctor.com.br\/cid\/k28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vivadoctor.com.br\/cid\/"},{"@type":"ListItem","position":2,"name":"K28 &#8211; \u00dalcera gastrojejunal"}]},{"@type":"Person","@id":"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1","name":"DoutorApp","sameAs":["https:\/\/vivadoctor.com.br\/cid","https:\/\/facebook.com\/doutorapp","https:\/\/instagram.com\/doutorapp"],"url":"https:\/\/vivadoctor.com.br\/cid\/author\/edimar\/"}]}},"_links":{"self":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1708"}],"collection":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/comments?post=1708"}],"version-history":[{"count":1,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1708\/revisions"}],"predecessor-version":[{"id":1709,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1708\/revisions\/1709"}],"wp:attachment":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/media?parent=1708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/categories?post=1708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/tags?post=1708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}