{"id":1999,"date":"2020-07-02T20:46:46","date_gmt":"2020-07-02T23:46:46","guid":{"rendered":"https:\/\/vivadoctor.com.br\/cid\/?p=1999"},"modified":"2020-07-02T20:46:51","modified_gmt":"2020-07-02T23:46:51","slug":"m23","status":"publish","type":"post","link":"https:\/\/vivadoctor.com.br\/cid\/m23\/","title":{"rendered":"M23 &#8211; Transtornos internos dos joelhos"},"content":{"rendered":"\n<p>M230 &#8211; Menisco c\u00edstico<\/p>\n\n\n\n<p>M231 &#8211; Menisco disc\u00f3ide (cong\u00eanito)<\/p>\n\n\n\n<p>M232 &#8211; Transtorno do menisco devido \u00e0 ruptura ou les\u00e3o antiga<\/p>\n\n\n\n<p>M233 &#8211; Outros transtornos do menisco<\/p>\n\n\n\n<p>M234 &#8211; Corpo flutuante no joelho<\/p>\n\n\n\n<p>M235 &#8211; Instabilidade cr\u00f4nica do joelho<\/p>\n\n\n\n<p>M236 &#8211; Outras rupturas espont\u00e2neas de ligamento(s) do joelho<\/p>\n\n\n\n<p>M238 &#8211; Outros transtornos internos do joelho<\/p>\n\n\n\n<p>M239 &#8211; Transtorno interno n\u00e3o especificado do joelho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M230 &#8211; Menisco c\u00edstico M231 &#8211; Menisco disc\u00f3ide (cong\u00eanito) M232 &#8211; Transtorno do menisco devido \u00e0 ruptura ou les\u00e3o antiga M233 &#8211; Outros transtornos do menisco M234 &#8211; Corpo flutuante no joelho M235 &#8211; Instabilidade cr\u00f4nica do joelho M236 &#8211; Outras rupturas espont\u00e2neas de ligamento(s) do joelho M238 &#8211; Outros transtornos internos do joelho M239<a class=\"more-link\" href=\"https:\/\/vivadoctor.com.br\/cid\/m23\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[163,144,159],"tags":[1746,3228,1485,3229],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M23 - Transtornos internos dos joelhos - Consulta CID 10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vivadoctor.com.br\/cid\/m23\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M23 - Transtornos internos dos joelhos - Consulta CID 10\" \/>\n<meta property=\"og:description\" content=\"M230 &#8211; Menisco c\u00edstico M231 &#8211; Menisco disc\u00f3ide (cong\u00eanito) M232 &#8211; Transtorno do menisco devido \u00e0 ruptura ou les\u00e3o antiga M233 &#8211; Outros transtornos do menisco M234 &#8211; Corpo flutuante no joelho M235 &#8211; Instabilidade cr\u00f4nica do joelho M236 &#8211; Outras rupturas espont\u00e2neas de ligamento(s) do joelho M238 &#8211; Outros transtornos internos do joelho M239Continue lendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vivadoctor.com.br\/cid\/m23\/\" \/>\n<meta property=\"og:site_name\" content=\"Consulta CID 10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/doutorapp\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/doutorapp\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T23:46:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-02T23:46:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DoutorApp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/\",\"name\":\"Consulta CID 10\",\"description\":\"Classifica\\u00e7\\u00e3o Internacional de Doen\\u00e7as\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/m23\/#webpage\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/m23\/\",\"name\":\"M23 - Transtornos internos dos joelhos - Consulta CID 10\",\"isPartOf\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\"},\"datePublished\":\"2020-07-02T23:46:46+00:00\",\"dateModified\":\"2020-07-02T23:46:51+00:00\",\"author\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1\"},\"breadcrumb\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/m23\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vivadoctor.com.br\/cid\/m23\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/m23\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/vivadoctor.com.br\/cid\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M23 &#8211; Transtornos internos dos joelhos\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1\",\"name\":\"DoutorApp\",\"sameAs\":[\"https:\/\/vivadoctor.com.br\/cid\",\"https:\/\/facebook.com\/doutorapp\",\"https:\/\/instagram.com\/doutorapp\"],\"url\":\"https:\/\/vivadoctor.com.br\/cid\/author\/edimar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M23 - Transtornos internos dos joelhos - Consulta CID 10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vivadoctor.com.br\/cid\/m23\/","og_locale":"pt_BR","og_type":"article","og_title":"M23 - Transtornos internos dos joelhos - Consulta CID 10","og_description":"M230 &#8211; Menisco c\u00edstico M231 &#8211; Menisco disc\u00f3ide (cong\u00eanito) M232 &#8211; Transtorno do menisco devido \u00e0 ruptura ou les\u00e3o antiga M233 &#8211; Outros transtornos do menisco M234 &#8211; Corpo flutuante no joelho M235 &#8211; Instabilidade cr\u00f4nica do joelho M236 &#8211; Outras rupturas espont\u00e2neas de ligamento(s) do joelho M238 &#8211; Outros transtornos internos do joelho M239Continue lendo &rarr;","og_url":"https:\/\/vivadoctor.com.br\/cid\/m23\/","og_site_name":"Consulta CID 10","article_publisher":"https:\/\/facebook.com\/doutorapp","article_author":"https:\/\/facebook.com\/doutorapp","article_published_time":"2020-07-02T23:46:46+00:00","article_modified_time":"2020-07-02T23:46:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"DoutorApp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/vivadoctor.com.br\/cid\/#website","url":"https:\/\/vivadoctor.com.br\/cid\/","name":"Consulta CID 10","description":"Classifica\u00e7\u00e3o Internacional de Doen\u00e7as","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/vivadoctor.com.br\/cid\/m23\/#webpage","url":"https:\/\/vivadoctor.com.br\/cid\/m23\/","name":"M23 - Transtornos internos dos joelhos - Consulta CID 10","isPartOf":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#website"},"datePublished":"2020-07-02T23:46:46+00:00","dateModified":"2020-07-02T23:46:51+00:00","author":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1"},"breadcrumb":{"@id":"https:\/\/vivadoctor.com.br\/cid\/m23\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vivadoctor.com.br\/cid\/m23\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vivadoctor.com.br\/cid\/m23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vivadoctor.com.br\/cid\/"},{"@type":"ListItem","position":2,"name":"M23 &#8211; Transtornos internos dos joelhos"}]},{"@type":"Person","@id":"https:\/\/vivadoctor.com.br\/cid\/#\/schema\/person\/7cf63ce50923b994a9cff427581f29e1","name":"DoutorApp","sameAs":["https:\/\/vivadoctor.com.br\/cid","https:\/\/facebook.com\/doutorapp","https:\/\/instagram.com\/doutorapp"],"url":"https:\/\/vivadoctor.com.br\/cid\/author\/edimar\/"}]}},"_links":{"self":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1999"}],"collection":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/comments?post=1999"}],"version-history":[{"count":1,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1999\/revisions"}],"predecessor-version":[{"id":2000,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts\/1999\/revisions\/2000"}],"wp:attachment":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/media?parent=1999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/categories?post=1999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/tags?post=1999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}