{"id":3853,"count":1,"description":"","link":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/","name":"cidretencaoplacenta","slug":"cidretencaoplacenta","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivos cidretencaoplacenta - Consulta CID 10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos cidretencaoplacenta - Consulta CID 10\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Consulta CID 10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/\",\"name\":\"Consulta CID 10\",\"description\":\"Classifica\\u00e7\\u00e3o Internacional de Doen\\u00e7as\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/#webpage\",\"url\":\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/\",\"name\":\"Arquivos cidretencaoplacenta - Consulta CID 10\",\"isPartOf\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/vivadoctor.com.br\/cid\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cidretencaoplacenta\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos cidretencaoplacenta - Consulta CID 10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos cidretencaoplacenta - Consulta CID 10","og_url":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/","og_site_name":"Consulta CID 10","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/vivadoctor.com.br\/cid\/#website","url":"https:\/\/vivadoctor.com.br\/cid\/","name":"Consulta CID 10","description":"Classifica\u00e7\u00e3o Internacional de Doen\u00e7as","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vivadoctor.com.br\/cid\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"CollectionPage","@id":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/#webpage","url":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/","name":"Arquivos cidretencaoplacenta - Consulta CID 10","isPartOf":{"@id":"https:\/\/vivadoctor.com.br\/cid\/#website"},"breadcrumb":{"@id":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vivadoctor.com.br\/cid\/tag\/cidretencaoplacenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vivadoctor.com.br\/cid\/"},{"@type":"ListItem","position":2,"name":"cidretencaoplacenta"}]}]}},"_links":{"self":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/tags\/3853"}],"collection":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vivadoctor.com.br\/cid\/wp-json\/wp\/v2\/posts?tags=3853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}